{"id":3425,"date":"2025-12-19T09:10:32","date_gmt":"2025-12-19T12:10:32","guid":{"rendered":"https:\/\/bibliocentral.uncoma.edu.ar\/?p=3425"},"modified":"2025-12-19T09:10:33","modified_gmt":"2025-12-19T12:10:33","slug":"desde-la-patagonia-difundiendo-saberes-numero-40-2025","status":"publish","type":"post","link":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/2025\/12\/19\/desde-la-patagonia-difundiendo-saberes-numero-40-2025\/","title":{"rendered":"Desde la patagonia. Difundiendo saberes N\u00famero 40 (2025)"},"content":{"rendered":"\n<p>Vol. 22 N\u00fam. 40 (2025)<\/p>\n\n\n\n<p>Una nueva publicaci\u00f3n de nuestra revista siempre nos llena de alegr\u00eda por m\u00faltiples motivos, entre ellos la posibilidad de compartir con nuestras\/os lectoras\/es las producciones de grupos que trabajan para promover el pensamiento cient\u00edfico. En este n\u00famero 40 nos permitimos contarles un poco sobre nosotros: somos un grupo de trabajo que, a lo largo de los m\u00e1s de veinte a\u00f1os de existencia de la revista, se ha ido renovando con el tiempo, pero que mantiene en com\u00fan algo muy profundo: quienes pasa-mos por aqu\u00ed dejamos parte de nuestro coraz\u00f3n en este espacio.<a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/issue\/view\/563\"><\/a><\/p>\n\n\n\n<p>Publicado: 2025-12-17<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"issueTocGalleyLabel\">N\u00famero completo<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/issue\/view\/563\/191\">Descargar PDF<\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">ART\u00cdCULO<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6847_7470_coverImage_es_ES.jpg\" alt=\"La pseudociencia se disfraza con la apariencia de la ciencia: adopta su lenguaje, sus s\u00edmbolos y su autoridad visual, pero oculta en su interior una ilusi\u00f3n que no resiste el escrutinio cr\u00edtico.\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6847\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6847\">LA FRAGILIDAD DE LA VERDAD Creemos saber, pero muchas veces solo repetimos. Este art\u00edculo invita a descubrir c\u00f3mo el autoenga\u00f1o y los falsos discursos cient\u00edficos moldean nuestras certezas en pleno siglo XXI.<\/a> Ulysses Paulino Albuquerque 2-7\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6847\/63099\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6848_7471_coverImage_es_ES.png\" alt=\"Tiempo de desarrollo de poblaciones de Chrysomya megacephala de diferentes localidades a diversas temperaturas. Los s\u00edmbolos representan los 15 estudios incluidos en el meta-an\u00e1lisis. Se observa que a la misma temperatura la duraci\u00f3n del ciclo de vida difiere seg\u00fan el lugar.\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6848\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6848\">MOSCAS EN LA ESCENA DEL CRIMEN Los insectos ayudan a las ciencias forenses a responder preguntas clave en investigaciones judiciales, aportando evidencia sobre el tiempo y las circunstancias de una muerte.<\/a> Ana Julia Pereira 8-15\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6848\/63098\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6849_7472_coverImage_es_ES.jpg\" alt=\"Diversidad de api\u00e1ceas en la Patagonia.\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6849\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6849\">EL PODER DE LAS API\u00c1CEAS En la Patagonia crecen plantas emparentadas con las zanahorias que podr\u00edan ser herramientas prometedoras en nuestra batalla contra los microorganismos pat\u00f3genos.<\/a> Santiago Reyes, Ariadna Tripaldi 16-20\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6849\/63101\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6850_7473_coverImage_es_ES.jpg\" alt=\"Secuencia del comportamiento alimentario de las medusas en la columna de agua. La medusa nada activamente mediante contracciones r\u00edtmicas de la campana (flecha naranja) y luego desciende pasivamente (flecha azul), lo que le permite aumentar el encuentro con las presas. Durante el nado, sus tent\u00e1culos se extienden y capturan el zooplancton. Una vez atrapada, la presa, es transportada hacia la cavidad g\u00e1strica por el brazo oral. En el recuadro ampliado se muestra el proceso de captura, ingesti\u00f3n y digesti\u00f3n de las presas.\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6850\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6850\">MEDUSA INVASORA EN PATAGONIA Una medusa de agua dulce proveniente de aguas c\u00e1lidas asi\u00e1ticas es avistada durante el verano en lagos templado-fr\u00edos andino patag\u00f3nicos.<\/a> Sharon Allen Dohle, Mariana Reissig, Patricia E. Garc\u00eda, Mar\u00eda del Carmen Di\u00e9guez 22\u201331\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6850\/63100\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6851_7474_coverImage_es_ES.png\" alt=\" Esquema de estructura cristalina peri\u00f3dica con impurezas (c\u00edrculos rojos).\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6851\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6851\">DEL ENIGMA A LA NANOESCALA El efecto Kondo explica el comportamiento extra\u00f1o de los electrones en metales con impurezas magn\u00e9ticas a bajas temperaturas. Este fen\u00f3meno ha impulsado tanto desarrollos te\u00f3ricos como aplicaciones en nanotecnolog\u00eda.<\/a> Diego P\u00e9rez Daroca, Pablo Roura-Bas 60-67\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6851\/63097\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6852_7475_coverImage_es_ES.png\" alt=\"Buenezas comestibles abundantes en Bariloche. Ejemplares frescos utilizadas en el taller.\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6852\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6852\">LAS INVASORAS AL PLATO Inspirados en estudios del investigador y divulgador Eduardo \u201cEddy\u201d Rapoport, realizamos un taller sobre invasiones biol\u00f3gicas y conocimiento local, revalorizando las \u201cbuenezas\u201d como alternativa alimenticia accesible frente al cambio ambiental.<\/a> Fernando N. C\u00e9spedes, Pablo A. Grimaldi, Adriana E. Rovere, Hermeson Carlos dos Santos, Let\u00edcia Elias, Ingrid da Silva Lima, Catalina Rico Lenta, Ana H. Ladio 68-75\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6852\/63096\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">REPORTAJE<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6855_7478_coverImage_es_ES.jpg\" alt=\"Mart\u00edn Brogger observa una estrella de la familia Brisingidae recolectada durante la expedici\u00f3n.\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6855\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6855\">CUANDO LA CIENCIA ES PASI\u00d3N DE MULTITUDES Reportaje a Mart\u00edn Brogger\u00a0<\/a> Gustavo Viozzi, Roc\u00edo Vega, Jorgelina Franzese 32-41\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6855\/63093\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">RESE\u00d1A DE LIBRO<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6853_7476_coverImage_es_ES.jpg\" alt=\"Tapa libro Historicamente\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6853\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6853\">Hist\u00f3ricamente. Claves para pensar (y contar) otras versiones del pasado<\/a> Roc\u00edo Ivanissevich 21\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6853\/63095\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6854_7477_coverImage_es_ES.jpg\" alt=\"Tapa libro Estudios sobre sociedad, econom\u00eda y territorio en Bariloche 1\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6854\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6854\">Estudios sobre sociedad, econom\u00eda y territorio en Bariloche I<\/a> Juan Manuel Chicaval 59\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6854\/63094\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">DESDE LA PATAGONIA<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6858_7481_coverImage_es_ES.jpg\" alt=\"A la izquierda, detalle de la platina del nanomanipulador que va en la c\u00e1mara del microscopio electr\u00f3nico de barrido, donde est\u00e1n sus actuadores piezoel\u00e9ctricos y las cuatro puntas de prueba. A la derecha, en la Sala limpia del INN-CAB, operando el Microscopio SEM y su nanomanipulador.\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6858\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6858\">LA ODISEA DEL 2001 Un viaje fant\u00e1stico por la nanociencia y nanotecnolog\u00eda.<\/a> Rodolfo D. S\u00e1nchez 42-45\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6858\/63105\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6859_7482_coverImage_es_ES.jpg\" alt=\"Salida de campo al humedal. \"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6859\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6859\">DIPLOMATURA EN HUMEDALES Una propuesta educativa que une saberes cient\u00edficos y comunitarios para valorar, comprender y proteger los humedales como espacios esenciales para la vida y el equilibrio ambiental regional.<\/a> Julieta Palacios, Silvina Iribarne, Ariel Gajardo1, Lucrecia Avil\u00e9s 54-58\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6859\/63102\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6860_7483_coverImage_es_ES.jpg\" alt=\"Catalina Rico Lenta compartiendo semillas locales de la Feria de Agricultores Familiares del  Nahuel Huapi, luego de un taller realizado  en el INIBIOMA.\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6860\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6860\">UN PREMIO A LA CIENCIA QUE ABRAZA LOS SABERES DE LOS AGRICULTORES FAMILIARES PATAG\u00d3NICOS<\/a> Ana H. Ladio 46-48\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6860\/63104\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6861_7484_coverImage_es_ES.jpg\" alt=\"Charla interactiva en los laboratorios del INIBIOMA.\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6861\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6861\">CIENCIA Y COMUNIDAD, LA HISTORIA DEL INIBIOMA ABIERTO Desde sus inicios hasta hoy, el INIBIOMA Abierto se ha consolidado como un proyecto institucional ampliamente participativo que acerca la ciencia a la sociedad, conectando comunidad, ciencia y educaci\u00f3n.<\/a> R. Daniel Garcia, Valeria L. Martin-Albarracin, Mar\u00eda Eugenia Ghio 49-53\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6861\/63103\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">TESIS<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6864_7487_coverImage_es_ES.jpg\" alt=\"Gonzalo Carnevale Tesista \"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6864\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6864\">APRENDIZAJE Y PLASTICIDAD NEURONAL<\/a> Gonzalo Carnevale 76-77\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6864\/63106\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">EN LAS LIBRER\u00cdAS<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6863_7486_coverImage_es_ES.png\" alt=\"Tapas de libros\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6863\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6863\">En las librer\u00edas<\/a> 78\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6863\/63107\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">ARTE<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><img decoding=\"async\" src=\"https:\/\/revele.uncoma.edu.ar\/public\/journals\/25\/submission_6862_7485_coverImage_es_ES.jpg\" alt=\"Imagen de Anahi Mariluan por Paulo Villacorta\"><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6862\"><\/a><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6862\">Anah\u00ed Rayen Mariluan<\/a> Desde la Patagonia\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/revele.uncoma.edu.ar\/index.php\/desdelapatagonia\/article\/view\/6862\/63108\">Descargar PDF<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Vol. 22 N\u00fam. 40 (2025) Una nueva publicaci\u00f3n de nuestra revista siempre nos llena de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,187,229,230,234],"tags":[],"class_list":["post-3425","post","type-post","status-publish","format-standard","hentry","category-blog","category-difundiendo-saberes","category-revele","category-revista","category-texto-completo"],"_links":{"self":[{"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3425"}],"version-history":[{"count":2,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3425\/revisions"}],"predecessor-version":[{"id":3427,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3425\/revisions\/3427"}],"wp:attachment":[{"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}