{"id":2102,"date":"2023-12-05T14:50:12","date_gmt":"2023-12-05T14:50:12","guid":{"rendered":"https:\/\/bibliocentral.uncoma.edu.ar\/?p=2102"},"modified":"2024-04-25T17:02:51","modified_gmt":"2024-04-25T17:02:51","slug":"prestamos-especiales-de-verano-2024","status":"publish","type":"post","link":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/2023\/12\/05\/prestamos-especiales-de-verano-2024\/","title":{"rendered":"PR\u00c9STAMOS ESPECIALES DE VERANO 2024"},"content":{"rendered":"\n<p>Los pr\u00e9stamos extendidos, son pr\u00e9stamos especiales que comienzan el lunes 11 de diciembre del 2023 para devolver el lunes 19 de febrero del 2024. <\/p>\n\n\n\n<p>Pensado para que los estudiantes  puedan aprovechar al m\u00e1ximo sus vacaciones, ya sea investigando, preparando finales o disfrutando de una lectura recreativa. <\/p>\n\n\n\n<p>Con esta modalidad se pueden llevar sin reserva, tres libros de c\u00e1tedra, m\u00e1s un libro de literatura, novelas, ensayos o poes\u00edas. <\/p>\n\n\n\n<p>\u00bfQu\u00e9 libro te va a acompa\u00f1ar estas vacaciones? Pod\u00e9s consultar todo el material disponible en el <a href=\"https:\/\/opac.uncoma.edu.ar\/\">cat\u00e1logo.<\/a><\/p>\n\n\n\n<p>\u00a1Aprovech\u00e1 a llevarte lo que necesit\u00e1s!<\/p>\n\n\n\n<p>Te esperamos de lunes a viernes de 9 a 18 h<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los pr\u00e9stamos extendidos, son pr\u00e9stamos especiales que comienzan el lunes 11 de diciembre del 2023&#8230;<\/p>\n","protected":false},"author":2,"featured_media":2103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[171,51,101,100],"class_list":["post-2102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-blog","tag-prestamos","tag-prestamos-especiales","tag-vacaciones-de-verano"],"_links":{"self":[{"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/2102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=2102"}],"version-history":[{"count":2,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/2102\/revisions"}],"predecessor-version":[{"id":2105,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/2102\/revisions\/2105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/2103"}],"wp:attachment":[{"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=2102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=2102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bibliocentral.uncoma.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=2102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}